{"id":1847,"date":"2025-10-15T15:19:25","date_gmt":"2025-10-15T18:19:25","guid":{"rendered":"https:\/\/araps.com.br\/?p=1847"},"modified":"2025-10-31T11:02:08","modified_gmt":"2025-10-31T14:02:08","slug":"alongue-se-com-a-araps","status":"publish","type":"post","link":"https:\/\/araps.com.br\/index.php\/2025\/10\/15\/alongue-se-com-a-araps\/","title":{"rendered":"Alongue-se com a ARAPS"},"content":{"rendered":"\n<p>O Alongamento<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Reduz as tens\u00f5es articulares provocadas por m\u00fasculos muito encurtados, que na maioria das vezes s\u00e3o respons\u00e1veis por problemas articulares (principalmente em idosos ou indiv\u00edduos que se viciam em posic\u00f5es erradas no dia-a-dia);<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Relaxa o corpo;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Amplia o relaxamento mental;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Proporciona maior consci\u00eancia corporal;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Deixa os movimentos mais soltos e f\u00e1ceis, melhorando a coordena\u00e7\u00e3o;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Previne les\u00f5es;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Prepara o corpo para atividades f\u00edsicas;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Ativa a circula\u00e7\u00e3o;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Reduz o risco de entorse articular ou les\u00e3o muscular;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Melhora e reduz o risco de problemas nas costas;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Ajuda no aquecimento, \u00e0 medida que eleva a temperatura do corpo;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Ajuda a liberar os movimentos bloqueados por tens\u00f5es emocionais.<\/li>\n<\/ul>\n\n\n\n<p><strong>AULAS DE ALONGAMENTO E RELAXAMENTO AQUI NA ARAPS, TODAS AS TERCAS E\u00a0QUINTAS\u00a0FEIRAS.<\/strong><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Alongamento AULAS DE ALONGAMENTO E RELAXAMENTO AQUI NA ARAPS, TODAS AS TERCAS E\u00a0QUINTAS\u00a0FEIRAS.<\/p>\n","protected":false},"author":1,"featured_media":1889,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[49,54,42],"class_list":["post-1847","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saude","tag-aposentados","tag-araps","tag-saude"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/araps.com.br\/wp-content\/uploads\/2025\/10\/alongue.png?fit=1024%2C576&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/araps.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/araps.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/araps.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/araps.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/araps.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1847"}],"version-history":[{"count":2,"href":"https:\/\/araps.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1847\/revisions"}],"predecessor-version":[{"id":1890,"href":"https:\/\/araps.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1847\/revisions\/1890"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/araps.com.br\/index.php\/wp-json\/wp\/v2\/media\/1889"}],"wp:attachment":[{"href":"https:\/\/araps.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1847"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/araps.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1847"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/araps.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}